{"id":2415,"date":"2025-03-15T19:19:21","date_gmt":"2025-03-15T19:19:21","guid":{"rendered":"https:\/\/www.dosers.nl\/?post_type=updates-cpt&#038;p=2415"},"modified":"2025-03-15T19:19:21","modified_gmt":"2025-03-15T19:19:21","slug":"t-kakelspektakel-2023","status":"publish","type":"updates-cpt","link":"https:\/\/www.dosers.nl\/en\/updates\/t-kakelspektakel-2023\/","title":{"rendered":"&#8216;t Kakelspektakel 2023"},"content":{"rendered":"","protected":false},"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/www.dosers.nl\/en\/wp-json\/wp\/v2\/updates-cpt\/2415"}],"collection":[{"href":"https:\/\/www.dosers.nl\/en\/wp-json\/wp\/v2\/updates-cpt"}],"about":[{"href":"https:\/\/www.dosers.nl\/en\/wp-json\/wp\/v2\/types\/updates-cpt"}],"wp:attachment":[{"href":"https:\/\/www.dosers.nl\/en\/wp-json\/wp\/v2\/media?parent=2415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}